{"id":7415,"date":"2019-02-18T09:50:22","date_gmt":"2019-02-18T12:50:22","guid":{"rendered":"http:\/\/entreriosbasquet.com\/site\/?p=7415"},"modified":"2019-02-18T09:50:22","modified_gmt":"2019-02-18T12:50:22","slug":"olimpia-volvio-al-triunfo-ante-atletico-tala","status":"publish","type":"post","link":"https:\/\/entreriosbasquet.com\/site\/2019\/02\/18\/olimpia-volvio-al-triunfo-ante-atletico-tala\/","title":{"rendered":"Olimpia volvi\u00f3 al triunfo ante Atl\u00e9tico Tala"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">Olimpia de Paran\u00e1 se reencontr\u00f3 con la victoria tras superar 66-61 a Atl\u00e9tico Tala en el \u201cHumberto Pietranera\u201d, por una jornada del Torneo Federal de B\u00e1squetbol. Nicolas Paciotti, autor de 18 puntos, fue el goleador del juego. El pr\u00f3ximo partido del CAO ser\u00e1 el jueves 21 de febrero, cuando se mida ante BH en Gualeguay.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">El inicio fue parejo y ambos intentaron desnivelar en la pintura. Carulla y Claud\u00e9 por parte del Olimpia, mientras que Echazarreta e Isaac Monti del lado talense.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">El tanteador qued\u00f3 5-4 y luego 9-8. No obstante, Nicolas Paciotti entr\u00f3 en acci\u00f3n y la balanza se inclin\u00f3 para el due\u00f1o de casa. Es que el perimetral corri\u00f3 la cancha, asisti\u00f3 a sus compa\u00f1eros, convirti\u00f3 desde larga distancia, y fue clave para que su equipo se quede con el primer cuarto por\u00a0<strong>21-12<\/strong>.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Cinco puntos consecutivos de Monti acercaron a la visita en el amanecer del segundo (21-17), aunque Claude y Rodr\u00edguez contestaron con dobles en el poste bajo y dejaron el pleito 25-17.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Durante los minutos posteriores ambos elencos estuvieron err\u00e1ticos y el marcador se estanc\u00f3. Con un triple de Rom\u00e1n Rodriguez el local tom\u00f3 diez puntos de distancia (31-21), sin embargo, los\u00a0<em>azules<\/em>\u00a0aprovecharon los errores de su adversario y de la mano de Echazarreta achicaron, y se fueron abajo por cuatro puntos al descanso largo (<strong>31-27<\/strong>).<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Con un doble de Claude en la pintura y una corrida de Alfonso, en un abrir y cerrar de ojos los paranaenses dejaron el pleito 35-27, aunque esta vez fue Monti quien respondi\u00f3 para los de Rosario del Tala (35-30 promediando el chico). De pronto, el\u00a0<em>azulgrana\u00a0<\/em>tuvo su mejor momento. Primero volvi\u00f3 a aparecer Paciotti en dos ocasiones desde 6.75, a lo que respondi\u00f3 Mateo con la misma receta. Aunque luego se hicieron fuertes en la zona pintada tanto Carulla como Claude. Es m\u00e1s, se sum\u00f3 Rodr\u00edguez, y el local se fue en ganancia al \u00faltimo cap\u00edtulo\u00a0<strong>53-38<\/strong>.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Durante la primera parte del cuarto definitivo la diferencia se mantuvo. Claude continu\u00f3 aportando para los de Paran\u00e1, mientras que la figura de Ver\u00f3n comenz\u00f3 a crecer en la visita (55-42). Agasse y Guanco hicieron lo propio desde afuera y la historia qued\u00f3 60-46, con 7\u2019 para el cierre.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">Sin embargo, los dirigidos por Santiago Vesco equivocaron los caminos, bajaron la efectividad y los conducidos por Guillermo Tasso se acercaron peligrosamente. Los talenses quedaron abajo por diez (60-50) y con un triple de Ver\u00f3n por siete (60-53). Es m\u00e1s, con una corrida de Echazarreta, y otro doble en el coraz\u00f3n de la pintura por parte de Ver\u00f3n, quedaron a una posesi\u00f3n (60-57), con 3\u201936\u201d por jugar, lo que gener\u00f3 pedido de tiempo muerto en el banco local.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">En el regreso, las decisiones volvieron a pasar por Rodr\u00edguez y Claude, y desde la l\u00ednea Olimpia sell\u00f3 el triunfo que finalmente fue por\u00a0<strong>66 a 61<\/strong>; lo que signific\u00f3 la sexta victoria de la temporada.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>-S\u00edntesis:<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Olimpia 66<\/strong>: Nicol\u00e1s Agasse 6, Rom\u00e1n Rodr\u00edguez 17, Alan Guanco 5, Baltazar Claude 13, Facundo Carulla 5, Tom\u00e1s G\u00f3mez 0, Le\u00f3n Alfonso 2, Pablo Pastori 0, Nicol\u00e1s Paciotti 18. DT: Santiago Vesco.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Atl\u00e9tico Tala 61:\u00a0<\/strong>Cristian Ver\u00f3n 8, Isaac Monti 16, Dami\u00e1n Echazarreta 13, Leandro Mateo 12, Guillermo Romero 8, Juan Jure 2, Andr\u00e9s Duval 2. DT: Guillermo Tasso.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Parciales:<\/strong>\u00a021-12, 31-27 y 53-38.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Jueces:<\/strong>\u00a0Virginia Peruchini \u2013 Romina Morales.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Comisionado t\u00e9cnico:<\/strong>\u00a0Ernesto Bottazzi.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Estadio:<\/strong>\u00a0Humberto Pietranera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olimpia de Paran\u00e1 se reencontr\u00f3 con la victoria tras superar 66-61 a Atl\u00e9tico Tala en el \u201cHumberto Pietranera\u201d, por una jornada del Torneo Federal de B\u00e1squetbol. Nicolas Paciotti, autor de 18 puntos, fue el goleador del juego. El pr\u00f3ximo partido del CAO ser\u00e1 el jueves 21 de febrero, cuando se mida ante BH en Gualeguay. [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7416,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[169,46,29],"_links":{"self":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/7415"}],"collection":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/comments?post=7415"}],"version-history":[{"count":1,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/7415\/revisions"}],"predecessor-version":[{"id":7417,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/7415\/revisions\/7417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media\/7416"}],"wp:attachment":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media?parent=7415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories?post=7415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/tags?post=7415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}