{"id":14807,"date":"2022-10-05T10:32:26","date_gmt":"2022-10-05T13:32:26","guid":{"rendered":"http:\/\/entreriosbasquet.com\/site\/?p=14807"},"modified":"2022-10-05T10:35:12","modified_gmt":"2022-10-05T13:35:12","slug":"la-union-se-llevo-el-cuadrangular-en-la-historica","status":"publish","type":"post","link":"https:\/\/entreriosbasquet.com\/site\/2022\/10\/05\/la-union-se-llevo-el-cuadrangular-en-la-historica\/","title":{"rendered":"La Uni\u00f3n se llev\u00f3 el cuadrangular en \u00abLa Hist\u00f3rica\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">Tras imponerse anoche 75-70 sobre Tom\u00e1s de Rocamora, La Uni\u00f3n de Col\u00f3n se alz\u00f3 con el Cuadrangular Costa del Uruguay que se disput\u00f3 este fin de semana en el estadio Gigante del Sur de la Rep\u00fablica del Puerto Viejo.<\/p>\n<p style=\"text-align: justify;\">Estudiantes de Concordia, por su lado, derrot\u00f3 a Parque Sur 81-70 y finaliz\u00f3 en el tercer lugar. El certamen de car\u00e1cter amistoso le sirvi\u00f3 a los cuatro equipos entrerrianos como preparaci\u00f3n de cara a la pr\u00f3xima Liga Argentina de B\u00e1squetbol.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #0000ff;\"><strong>LA UNI\u00d3N GAN\u00d3 EN \u00abLA HIST\u00d3RICA\u00bb<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">En el estadio de Parque Sur,\u00a0La Uni\u00f3n de Col\u00f3n super\u00f3\u00a075-70 a Tom\u00e1s de Rocamora y gan\u00f3 el cuadrangular de preparaci\u00f3n de cara a lo que ser\u00e1 la venidera edici\u00f3n de la Liga Argentina de B\u00e1squetbol.<\/p>\n<p style=\"text-align: justify;\">El partido entre los Rojos tuvo mucha paridad a lo largo de los 40 minutos pero el equipo de Mart\u00edn Gustavino fue el que hilvan\u00f3 mayor y mejor cantidad de buenos pasajes. Por eso se termin\u00f3 quedando merecidamente con el triunfo. Rocamora no tuvo la misma fluidez ofensiva que en los dos amistosos anteriores aunque s\u00ed mostr\u00f3 buenos momentos que, por ejemplo, le permitieron remontar desventajas de hasta 9 puntos.<\/p>\n<p style=\"text-align: justify;\">El primer cuarto se lo qued\u00f3 La Uni\u00f3n 21-18 dejando en claro que con su base campeona de la Liga Federal y las incorporaciones que hizo ser\u00e1 un hueso duro de roer para varios. El base Guido Cabrera, con 3 tres triples en este tramo y 10 puntos en toral, fue el destacado. Rocamora tuvo a Franco Ferrar\u00eda como su principal arma de gol con 5 unidades.<\/p>\n<p style=\"text-align: justify;\">En los pasajes iniciales del segundo cuarto Rocamora volvi\u00f3 a pasar al frente gracias a un par de acciones de Thiago Dasso, primero un triple y enseguida un doble para pasar al frente 26-24. Pero le dur\u00f3 poco la alegr\u00eda porque dos bombazos de Emilio Gim\u00e9nez le dieron a La Uni\u00f3n otra vez el liderazgo. Agust\u00edn Pujol us\u00f3 un tiempo muerto, a la vuelta no hubo mejor\u00eda y La Uni\u00f3n qued\u00f3 35-26 arriba. Al descanso largo se marcharon 37-32 igualmente.<\/p>\n<p style=\"text-align: justify;\">Cuando volvieron a jugar los triples estuvieron a la orden del d\u00eda, Verbauwede y Catal\u00edn por un lado; Lavoratornuovo y Conti por el otro. El tablero qued\u00f3 49-40 para los colonenses y Pujol us\u00f3 otro tiempo muerto. Esta vez s\u00ed el equipo reaccion\u00f3 y empez\u00f3 a limar la diferencia. Jug\u00f3 mejor, defendi\u00f3 con m\u00e1s rudeza, encontr\u00f3 triples en Tarrag\u00f3 y Cavall\u00edn y dej\u00f3 el tablero igualado 55-55 de cara al \u00faltimo cuarto.<\/p>\n<p style=\"text-align: justify;\">Pero todo lo bueno que hizo en el cierre del parcial anterior Rocamora lo dej\u00f3 caer en el inicio del \u00faltimo cuarto. La Uni\u00f3n le meti\u00f3 un parcial 8-0 y otra vez a empezar de nuevo tras el pedido de minuto (63-55). Nuevamente lleg\u00f3 la reacci\u00f3n para dejar el partido a solo un simple (63-62) e incluso con la chance de volver a pasar al frente. No se dio y ya en la recta final La Uni\u00f3n se mostr\u00f3 m\u00e1s preciso y efectivo ante un Rocamora que cometi\u00f3 un par de errores y despu\u00e9s no pudo recomponerse.<\/p>\n<p style=\"text-align: justify;\">El goleador de la noche fue Joaqu\u00edn Acu\u00f1a con 16 puntos, seguido por C\u00e9sar Lavoratornuovo con 15. En La Uni\u00f3n tambi\u00e9n llegaron al doble d\u00edgito Guido Cabrera (12) y Emilio Gim\u00e9nez (10). En Rocamora el m\u00e1s efectivo fue Tom\u00e1s Verbauwede con 11 puntos, en tanto que sumaron 10 cada uno Franco Ferrar\u00eda, Justo Catal\u00edn y Agust\u00edn Cavall\u00edn. El pr\u00f3ximo mi\u00e9rcoles ambos equipos volver\u00e1n a enfrentarse, ahora en cancha de La Uni\u00f3n, desde las 21.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras imponerse anoche 75-70 sobre Tom\u00e1s de Rocamora, La Uni\u00f3n de Col\u00f3n se alz\u00f3 con el Cuadrangular Costa del Uruguay que se disput\u00f3 este fin de semana en el estadio Gigante del Sur de la Rep\u00fablica del Puerto Viejo. Estudiantes de Concordia, por su lado, derrot\u00f3 a Parque Sur 81-70 y finaliz\u00f3 en el tercer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[],"_links":{"self":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/14807"}],"collection":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/comments?post=14807"}],"version-history":[{"count":3,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/14807\/revisions"}],"predecessor-version":[{"id":14811,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/14807\/revisions\/14811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media\/14808"}],"wp:attachment":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media?parent=14807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories?post=14807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/tags?post=14807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}