{"id":14796,"date":"2022-09-28T09:36:36","date_gmt":"2022-09-28T12:36:36","guid":{"rendered":"http:\/\/entreriosbasquet.com\/site\/?p=14796"},"modified":"2022-09-28T09:36:36","modified_gmt":"2022-09-28T12:36:36","slug":"liga-femenina-rocamora-inicio-la-pretemporada","status":"publish","type":"post","link":"https:\/\/entreriosbasquet.com\/site\/2022\/09\/28\/liga-femenina-rocamora-inicio-la-pretemporada\/","title":{"rendered":"Liga Femenina: Rocamora inici\u00f3 la pretemporada"},"content":{"rendered":"<p style=\"text-align: justify;\">Las Rojas volvieron a los entrenamientos pensando en la La Liga Nacional Femenina de B\u00e1squet en su temporada 2022\/23. En la c\u00e1lida noche del martes la entrenadora Laura Gonz\u00e1lez juntos a dirigentes\/as le dio la bienvenida al plantel y cuerpo t\u00e9cnico. Habr\u00e1 una intensa semana de trabajo hasta el 12 de octubre a cargo del Preparador F\u00edsico Mateo Caffa.<\/p>\n<p style=\"text-align: justify;\">El plantel Femenino del Tom\u00e1s de Rocamora comenz\u00f3 con los trabajos en el Estadio Julio C\u00e9sar Paccagnella. Con la presencia de todo su cuerpo t\u00e9cnico, el Rojo entren\u00f3 por la noche como estaba previsto con un plantel repleto de juveniles.<\/p>\n<p style=\"text-align: justify;\">El conjunto representante de la provincia en la m\u00e1xima categor\u00eda del b\u00e1squet femenino tendr\u00e1 15 d\u00edas de una dur\u00edsima pretemporada a cargo del Preparador F\u00edsico Mateo Caffa.<\/p>\n<p style=\"text-align: justify;\">La apuesta y la expectativa de Rocamora en la previa en una nueva Liga Nacional Femenina es tan importante y especial como las todas la Ligas que a participado a trav\u00e9s de la vital gesti\u00f3n directiva de la instituci\u00f3n, desde contar con la estructura adecuada, Rocamora sigue dando pasos adelante m\u00e1s que importante en el que ya no es un proyecto institucional si no una realidad.<\/p>\n<p style=\"text-align: justify;\">Para esta temporada conserv\u00f3 parte de su columna vertebral con su capitana Antonella Gonz\u00e1lez, Irina Figueroa, Ail\u00e9n Ayala. El resto de las jugadoras, todas formadas y nutridas en el club con Paula Santini, Delfina Cergneux. Clara Monta\u00f1ana, , In\u00e9s Fern\u00e1ndez, Melanie y Delsart Izaguirre que este a\u00f1o tendr\u00e1n mas minutos para ser protagonista de esta Liga que tendr\u00e1 12 equipos y dar\u00e1 inicio el pr\u00f3ximo 28 de octubre. Como punto fuerte y m\u00e1s importante para fortalecer la estructura, 9 clubes se comprometieron a participar en los pr\u00f3ximos 4 a\u00f1os de La Liga Femenina: Rocamora, Ameghino, Berazategui, Instituto, Montmartre, Obras, Pac\u00edfico, Quimsa y Riachuelo<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>La\u00a0competencia<\/strong><\/p>\n<p style=\"text-align: justify;\">El formato de la competici\u00f3n tendr\u00e1 a los 12 clubes divididos en dos zonas, reparti\u00e9ndose en Conferencia Norte (6 equipos) y Conferencia Sur (6 equipos). La Norte estar\u00e1 conformada por Amehino, Instituto,\u00a0 Montmartre, Ol\u00edmpico, Quimsa y Riachuelo. La Sur se encontrar\u00e1 integrada por Berazategui, Ferro, Obras Basket, Pac\u00edfico, Uni\u00f3n Florida y Rocamora.<\/p>\n<p style=\"text-align: justify;\">El certamen comenzar\u00e1 el pr\u00f3ximo 28 de octubre, con un formato de dos rondas de ida y vuelta por conferencia. Cada equipo disputar\u00e1 un total de 20 partidos en la etapa regular (un equipo se enfrentar\u00e1 cuatro veces ante el mismo rival en la serie regular). Dicha fase regular comprender\u00e1 la totalidad de ambas rondas culminar\u00e1 a finales de enero. Luego llegar\u00e1n los playoffs, con una etapa de play-in, playoffs de semifinales y final de conferencia, y la serie definici\u00f3n por el campeonato.<\/p>\n<p style=\"text-align: justify;\">La primera ronda del torneo est\u00e1 pautada para concluir el 26 de noviembre, y de esta primera etapa se clasificar\u00e1n los dos mejores de cada conferencia a un Final 4 a jugarse los d\u00edas 16 y 17 de diciembre. Luego de jugarse aquel Final 4 y hasta el 13 de enero la competici\u00f3n entrar\u00e1 en un receso por las fiestas navide\u00f1as, para luego retomar el calendario hasta concluir la segunda ronda a fines de enero.<\/p>\n<p style=\"text-align: justify;\">Una vez finalizada la fase regular, los tres mejores posicionados de cada conferencia se clasificar\u00e1n directamente a playoffs, mientras que los ubicados en los puestos 4 y 5 de cada zona disputar\u00e1n el play-in, a partido \u00fanico en cancha del mejor clasificado. De ese play-in saldr\u00e1 un equipo clasificado a playoffs, que se sumar\u00e1 a los restantes tres elencos y disputar\u00e1n las semifinales de conferencia al mejor de 3 partidos en formato 1-2.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Rojas volvieron a los entrenamientos pensando en la La Liga Nacional Femenina de B\u00e1squet en su temporada 2022\/23. En la c\u00e1lida noche del martes la entrenadora Laura Gonz\u00e1lez juntos a dirigentes\/as le dio la bienvenida al plantel y cuerpo t\u00e9cnico. Habr\u00e1 una intensa semana de trabajo hasta el 12 de octubre a cargo del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/14796"}],"collection":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/comments?post=14796"}],"version-history":[{"count":1,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/14796\/revisions"}],"predecessor-version":[{"id":14798,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/14796\/revisions\/14798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media\/14797"}],"wp:attachment":[{"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media?parent=14796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories?post=14796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/tags?post=14796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}