{"id":1470,"date":"2017-07-22T23:00:28","date_gmt":"2017-07-23T02:00:28","guid":{"rendered":"http:\/\/entreriosbasquet.com\/site\/?p=1470"},"modified":"2017-07-22T23:01:13","modified_gmt":"2017-07-23T02:01:13","slug":"sebastian-picton-es-nueva-ficha-de-la-union","status":"publish","type":"post","link":"http:\/\/entreriosbasquet.com\/site\/2017\/07\/22\/sebastian-picton-es-nueva-ficha-de-la-union\/","title":{"rendered":"Sebasti\u00e1n Picton es nueva ficha de La Uni\u00f3n"},"content":{"rendered":"<p style=\"text-align: justify;\">La Uni\u00f3n confirm\u00f3 la contrataci\u00f3n del alero Sebasti\u00e1n Picton para la temporada 17\/18 La Liga Argentina, como pasar\u00e1 a conocerse ahora el hist\u00f3rico Torneo Nacional de Ascenso.<\/p>\n<p style=\"text-align: justify;\">El nuevo jugador del Rojo naci\u00f3 en Resistencia (Chaco), tiene 25 a\u00f1os y mide 1,97 metros. Tiene pasos por Ciclista de Jun\u00edn, Ol\u00edmpico de La Banda (Liga A), Villa \u00c1ngela B\u00e1sket y la \u00faltima temporada jug\u00f3 en su ciudad natal para Hind\u00fa.<\/p>\n<p style=\"text-align: justify;\">En la \u00faltima campa\u00f1a, el jugador promedi\u00f3 7,7 puntos y 3,6 rebotes en algo m\u00e1s de 17 minutos en cancha en un equipo que perdi\u00f3 la final de la Conferencia Norte con el campe\u00f3n de la categor\u00eda Comunicaciones de Mercedes (Corrientes).<\/p>\n<p style=\"text-align: justify;\">Cristian Santander ya tiene seis fechas confirmadas y solamente le restan dos para completar el plantel, un interno y un jugador sub23 que ser\u00eda perimetral.<\/p>\n<p style=\"text-align: justify;\"><strong>Plantel<\/strong><\/p>\n<p style=\"text-align: justify;\">Bases: \u00c1lvaro Merlo (sub23) y Lautaro Fraga<\/p>\n<p style=\"text-align: justify;\">Escolta: Alejo Crotti<\/p>\n<p style=\"text-align: justify;\">Alero: Sebasti\u00e1n Picton<\/p>\n<p style=\"text-align: justify;\">Internos: Facundo Mendoza y Jeffrey Parker.<\/p>\n<p style=\"text-align: justify;\">Entrenador: Cristian Santander<\/p>\n<p style=\"text-align: justify;\">Asistente T\u00e9cnico: Jerem\u00edas Zutti\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Uni\u00f3n confirm\u00f3 la contrataci\u00f3n del alero Sebasti\u00e1n Picton para la temporada 17\/18 La Liga Argentina, como pasar\u00e1 a conocerse ahora el hist\u00f3rico Torneo Nacional de Ascenso. El nuevo jugador del Rojo naci\u00f3 en Resistencia (Chaco), tiene 25 a\u00f1os y mide 1,97 metros. Tiene pasos por Ciclista de Jun\u00edn, Ol\u00edmpico de La Banda (Liga A), [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1471,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11],"tags":[103],"_links":{"self":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/1470"}],"collection":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/comments?post=1470"}],"version-history":[{"count":2,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/1470\/revisions"}],"predecessor-version":[{"id":1473,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/1470\/revisions\/1473"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media\/1471"}],"wp:attachment":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media?parent=1470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories?post=1470"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/tags?post=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}