{"id":11311,"date":"2020-11-25T10:19:00","date_gmt":"2020-11-25T13:19:00","guid":{"rendered":"http:\/\/entreriosbasquet.com\/site\/?p=11311"},"modified":"2020-11-25T10:19:00","modified_gmt":"2020-11-25T13:19:00","slug":"solanas-jugamos-en-equipo-y-cada-uno-encontro-su-rol","status":"publish","type":"post","link":"http:\/\/entreriosbasquet.com\/site\/2020\/11\/25\/solanas-jugamos-en-equipo-y-cada-uno-encontro-su-rol\/","title":{"rendered":"Solanas: \u00abJugamos en equipo y cada uno encontr\u00f3 su rol\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">San Mart\u00edn es el l\u00edder de la Conferencia Norte y se mantiene invicto en este inicio de temporada de la Liga Nacional de B\u00e1squetbol. Antes del parate, el escolta entrerriano Mat\u00edas Solanas analiz\u00f3 el presente del equipo:<strong><em>\u00a0\u201cEl an\u00e1lisis de las primeras fechas es muy bueno y positivo, logramos lo que trabajamos los d\u00edas previos a ir a competir, jugamos en equipo, cada uno encontr\u00f3 su rol, esas fueron las claves\u201d.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Y agreg\u00f3 una de las figuras del equipo:\u00a0<strong><em>\u201cJugamos bien en defensa y ataque. Adem\u00e1s, estuvimos a la altura en el plano f\u00edsico, despu\u00e9s de tanto tiempo sin jugar sab\u00edamos que no iba a ser f\u00e1cil, pero lo hicimos muy bien\u201d<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify;\">San Mart\u00edn gan\u00f3 los ocho partidos que disput\u00f3 durante la primera parte de la competencia, siendo el \u00fanico invicto en la Conferencia Norte. Y Solanas promedi\u00f3 16.2 puntos por juego en 30,5 minutos en cancha, en los 6 partidos que le toc\u00f3 jugar en este inicio positivo del equipo correntino.<\/p>\n<p style=\"text-align: justify;\">El actual goleador\u00a0<em>\u201crojinegro\u201d<\/em>\u00a0dijo adem\u00e1s:<strong><em>\u00a0\u201cSab\u00edamos que ten\u00edamos mucha confianza en nosotros y en lo trabajado anteriormente, vamos a aprovechar estos d\u00edas para entrenar al m\u00e1ximo y mantener el nivel que tenemos, trabajar para mejorar lo que no nos sal\u00eda, este parate nos viene bien para seguir mejorando\u201d<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify;\">Sin dudas que en esta temporada volver\u00e1 a sumar minutos y confirmar su experiencia en el equipo a pesar de su edad (21 a\u00f1os):<strong><em>\u00a0\u201cMe siento muy c\u00f3modo en mi rol, el equipo me da confianza y puedo jugar tranquilo, siempre intentando sumar para el equipo desde el lugar que me toque\u201d<\/em><\/strong>.<\/p>\n<p style=\"text-align: justify;\">Para cerrar, sobre el esguince que sufri\u00f3 en el partido con Libertad de Sunchales, Solanas coment\u00f3:\u00a0<em><strong>\u201cme encuentro muy bien, trabajamos mucho con nuestro kinesi\u00f3logo en Buenos Aires y los pr\u00f3ximos d\u00edas voy a dedicarme a la recuperaci\u00f3n para poder volver entrenar con normalidad muy pronto\u201d<\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Semana de trabajos en el \u201cFort\u00edn Rojinegro\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">El plantel de San Mart\u00edn regres\u00f3 en los \u00faltimos d\u00edas a la ciudad de Corrientes luego de la interrupci\u00f3n de la Liga Nacional de B\u00e1squetbol que retomar\u00e1 actividades los primeros d\u00edas de diciembre.<\/p>\n<p style=\"text-align: justify;\">Luego de realizarse los estudios correspondientes, el lunes por la tarde entrenaron en el Fort\u00edn Rojinegro y mantendr\u00e1n una rutina de trabajo en doble turno durante el tiempo que se encuentren en la ciudad.<\/p>\n<p style=\"text-align: justify;\">El jugador Franco Alorda y el asistente t\u00e9cnico Ariel Checcenelli se encuentran en Buenos Aires cumpliendo aislamiento, debido a que dieron positivo de COVID-19 en los \u00faltimos estudios realizados al plantel antes de la suspensi\u00f3n de La Liga.<\/p>\n<p style=\"text-align: justify;\">En caso de presentar hisopados con resultados negativos en los pr\u00f3ximos d\u00edas, regresar\u00e1n a Corrientes para sumarse al plantel.<\/p>\n<p style=\"text-align: justify;\">En tanto, Javier Saiz se encuentra concentrado con la Selecci\u00f3n Argentina que jugar\u00e1 la etapa clasificatoria a la Americup 2022 el pr\u00f3ximo 27 y 28 de noviembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Mart\u00edn es el l\u00edder de la Conferencia Norte y se mantiene invicto en este inicio de temporada de la Liga Nacional de B\u00e1squetbol. Antes del parate, el escolta entrerriano Mat\u00edas Solanas analiz\u00f3 el presente del equipo:\u00a0\u201cEl an\u00e1lisis de las primeras fechas es muy bueno y positivo, logramos lo que trabajamos los d\u00edas previos a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[12],"tags":[],"_links":{"self":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/11311"}],"collection":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/comments?post=11311"}],"version-history":[{"count":1,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/11311\/revisions"}],"predecessor-version":[{"id":11313,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts\/11311\/revisions\/11313"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media\/11312"}],"wp:attachment":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/media?parent=11311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories?post=11311"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/tags?post=11311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}