{"id":131,"count":19,"description":"Campeonato Argentino de Mayores de Neuqu\u00e9n 2017","link":"http:\/\/entreriosbasquet.com\/site\/category\/argentinos\/mayores-neuquen-2017\/","name":"NEUQUEN 2017","slug":"mayores-neuquen-2017","taxonomy":"category","parent":22,"meta":[],"_links":{"self":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories\/131"}],"collection":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/categories\/22"}],"wp:post_type":[{"href":"http:\/\/entreriosbasquet.com\/site\/wp-json\/wp\/v2\/posts?categories=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}